{"id":1143,"date":"2016-10-11T14:07:24","date_gmt":"2016-10-11T14:07:24","guid":{"rendered":"http:\/\/delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg"},"modified":"2016-10-11T14:07:24","modified_gmt":"2016-10-11T14:07:24","slug":"nota-blog","status":"inherit","type":"attachment","link":"https:\/\/ovh.delfinoglobal.com\/pt\/delfino-global-una-empresa-centenaria\/nota-blog\/","title":{"rendered":"nota-blog"},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1143","attachment","type-attachment","status-inherit","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"pt","enabled_languages":["es","en","pt"],"languages":{"es":{"title":true},"en":{"title":false},"pt":{"title":false}}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Mariana L\u00f3pez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ovh.delfinoglobal.com\/pt\/delfino-global-una-empresa-centenaria\/nota-blog\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_PT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Delfino Global |\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"nota-blog | Delfino Global\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ovh.delfinoglobal.com\/pt\/delfino-global-una-empresa-centenaria\/nota-blog\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-10-11T14:07:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-10-11T14:07:24+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"nota-blog | Delfino Global\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/delfino-global-una-empresa-centenaria\\\/nota-blog\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/delfino-global-una-empresa-centenaria\\\/nota-blog\\\/#listItem\",\"name\":\"nota-blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/delfino-global-una-empresa-centenaria\\\/nota-blog\\\/#listItem\",\"position\":2,\"name\":\"nota-blog\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/delfino-global-una-empresa-centenaria\\\/nota-blog\\\/#itempage\",\"url\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/delfino-global-una-empresa-centenaria\\\/nota-blog\\\/\",\"name\":\"nota-blog | Delfino Global\",\"inLanguage\":\"pt-PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/delfino-global-una-empresa-centenaria\\\/nota-blog\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/author\\\/mariana\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/author\\\/mariana\\\/#author\"},\"datePublished\":\"2016-10-11T14:07:24+00:00\",\"dateModified\":\"2016-10-11T14:07:24+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/#organization\",\"name\":\"Delfino Global\",\"url\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/author\\\/mariana\\\/#author\",\"url\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/author\\\/mariana\\\/\",\"name\":\"Mariana L\\u00f3pez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/delfino-global-una-empresa-centenaria\\\/nota-blog\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/31cb53ee86b5bb8760b61215b6c3b22f575562095ff1656f49d49044505221f6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Mariana L\\u00f3pez\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/\",\"name\":\"Delfino Global\",\"inLanguage\":\"pt-PT\",\"publisher\":{\"@id\":\"https:\\\/\\\/ovh.delfinoglobal.com\\\/pt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"nota-blog | Delfino Global","description":"","canonical_url":"https:\/\/ovh.delfinoglobal.com\/pt\/delfino-global-una-empresa-centenaria\/nota-blog\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ovh.delfinoglobal.com\/pt\/delfino-global-una-empresa-centenaria\/nota-blog\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ovh.delfinoglobal.com\/pt#listItem","position":1,"name":"Inicio","item":"https:\/\/ovh.delfinoglobal.com\/pt","nextItem":{"@type":"ListItem","@id":"https:\/\/ovh.delfinoglobal.com\/pt\/delfino-global-una-empresa-centenaria\/nota-blog\/#listItem","name":"nota-blog"}},{"@type":"ListItem","@id":"https:\/\/ovh.delfinoglobal.com\/pt\/delfino-global-una-empresa-centenaria\/nota-blog\/#listItem","position":2,"name":"nota-blog","previousItem":{"@type":"ListItem","@id":"https:\/\/ovh.delfinoglobal.com\/pt#listItem","name":"Inicio"}}]},{"@type":"ItemPage","@id":"https:\/\/ovh.delfinoglobal.com\/pt\/delfino-global-una-empresa-centenaria\/nota-blog\/#itempage","url":"https:\/\/ovh.delfinoglobal.com\/pt\/delfino-global-una-empresa-centenaria\/nota-blog\/","name":"nota-blog | Delfino Global","inLanguage":"pt-PT","isPartOf":{"@id":"https:\/\/ovh.delfinoglobal.com\/pt\/#website"},"breadcrumb":{"@id":"https:\/\/ovh.delfinoglobal.com\/pt\/delfino-global-una-empresa-centenaria\/nota-blog\/#breadcrumblist"},"author":{"@id":"https:\/\/ovh.delfinoglobal.com\/pt\/author\/mariana\/#author"},"creator":{"@id":"https:\/\/ovh.delfinoglobal.com\/pt\/author\/mariana\/#author"},"datePublished":"2016-10-11T14:07:24+00:00","dateModified":"2016-10-11T14:07:24+00:00"},{"@type":"Organization","@id":"https:\/\/ovh.delfinoglobal.com\/pt\/#organization","name":"Delfino Global","url":"https:\/\/ovh.delfinoglobal.com\/pt\/"},{"@type":"Person","@id":"https:\/\/ovh.delfinoglobal.com\/pt\/author\/mariana\/#author","url":"https:\/\/ovh.delfinoglobal.com\/pt\/author\/mariana\/","name":"Mariana L\u00f3pez","image":{"@type":"ImageObject","@id":"https:\/\/ovh.delfinoglobal.com\/pt\/delfino-global-una-empresa-centenaria\/nota-blog\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/31cb53ee86b5bb8760b61215b6c3b22f575562095ff1656f49d49044505221f6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Mariana L\u00f3pez"}},{"@type":"WebSite","@id":"https:\/\/ovh.delfinoglobal.com\/pt\/#website","url":"https:\/\/ovh.delfinoglobal.com\/pt\/","name":"Delfino Global","inLanguage":"pt-PT","publisher":{"@id":"https:\/\/ovh.delfinoglobal.com\/pt\/#organization"}}]},"og:locale":"pt_PT","og:site_name":"Delfino Global |","og:type":"article","og:title":"nota-blog | Delfino Global","og:url":"https:\/\/ovh.delfinoglobal.com\/pt\/delfino-global-una-empresa-centenaria\/nota-blog\/","article:published_time":"2016-10-11T14:07:24+00:00","article:modified_time":"2016-10-11T14:07:24+00:00","twitter:card":"summary","twitter:title":"nota-blog | Delfino Global"},"aioseo_meta_data":{"post_id":"1143","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-07 02:24:23","updated":"2025-07-07 19:10:51","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ovh.delfinoglobal.com\/pt\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tnota-blog\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/ovh.delfinoglobal.com\/pt"},{"label":"nota-blog","link":"https:\/\/ovh.delfinoglobal.com\/pt\/delfino-global-una-empresa-centenaria\/nota-blog\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>nota-blog - Delfino Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"nota-blog - Delfino Global\" \/>\n<meta property=\"og:url\" content=\"https:\/\/delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Delfino Global\" \/>\n<meta property=\"og:image\" content=\"https:\/\/delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"197\" \/>\n\t<meta property=\"og:image:height\" content=\"126\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/delfinoglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/nota-blog.jpg\",\"url\":\"https:\\\/\\\/delfinoglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/nota-blog.jpg\",\"name\":\"nota-blog - Delfino Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.delfinoglobal.com\\\/en\\\/#website\"},\"datePublished\":\"2016-10-11T14:07:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/delfinoglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/nota-blog.jpg#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/delfinoglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/nota-blog.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/delfinoglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/nota-blog.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.delfinoglobal.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Delfino Global: \u00abUna empresa centenaria\u00bb\",\"item\":\"https:\\\/\\\/delfinoglobal.com\\\/delfino-global-una-empresa-centenaria\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"nota-blog\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.delfinoglobal.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.delfinoglobal.com\\\/en\\\/\",\"name\":\"Delfino Global\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.delfinoglobal.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"nota-blog - Delfino Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg","og_locale":"pt_PT","og_type":"article","og_title":"nota-blog - Delfino Global","og_url":"https:\/\/delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg","og_site_name":"Delfino Global","og_image":[{"width":197,"height":126,"url":"https:\/\/delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg","url":"https:\/\/delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg","name":"nota-blog - Delfino Global","isPartOf":{"@id":"https:\/\/www.delfinoglobal.com\/en\/#website"},"datePublished":"2016-10-11T14:07:24+00:00","breadcrumb":{"@id":"https:\/\/delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.delfinoglobal.com\/en\/"},{"@type":"ListItem","position":2,"name":"Delfino Global: \u00abUna empresa centenaria\u00bb","item":"https:\/\/delfinoglobal.com\/delfino-global-una-empresa-centenaria\/"},{"@type":"ListItem","position":3,"name":"nota-blog"}]},{"@type":"WebSite","@id":"https:\/\/www.delfinoglobal.com\/en\/#website","url":"https:\/\/www.delfinoglobal.com\/en\/","name":"Delfino Global","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.delfinoglobal.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ovh.delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"197\" height=\"126\" src=\"https:\/\/ovh.delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":197,"height":126,"file":"2016\/10\/nota-blog.jpg","sizes":{"thumbnail":{"file":"nota-blog-150x126.jpg","width":150,"height":126,"mime_type":"image\/jpeg","source_url":"https:\/\/ovh.delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog-150x126.jpg"},"full":{"file":"nota-blog.jpg","width":197,"height":126,"mime_type":"image\/jpeg","source_url":"https:\/\/ovh.delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":1139,"source_url":"https:\/\/ovh.delfinoglobal.com\/wp-content\/uploads\/2016\/10\/nota-blog.jpg","filename":"nota-blog.jpg","filesize":40317,"_links":{"self":[{"href":"https:\/\/ovh.delfinoglobal.com\/pt\/wp-json\/wp\/v2\/media\/1143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ovh.delfinoglobal.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ovh.delfinoglobal.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ovh.delfinoglobal.com\/pt\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ovh.delfinoglobal.com\/pt\/wp-json\/wp\/v2\/comments?post=1143"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1139,"href":"https:\/\/ovh.delfinoglobal.com\/pt\/wp-json\/wp\/v2\/posts\/1139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}